{"id":299,"count":19,"description":"","link":"https:\/\/www.deshe-kavua.co.il\/en\/category\/garden-products-en\/","name":"Garden Products","slug":"garden-products-en","taxonomy":"category","parent":0,"meta":[],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Garden Products<\/title>\n<meta name=\"description\" content=\"\u05d3\u05e9\u05d0 \u05e7\u05d1\u05d5\u05e2\" \/>\n<meta name=\"robots\" content=\"noindex, follow\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Garden Products\" \/>\n<meta property=\"og:description\" content=\"\u05d3\u05e9\u05d0 \u05e7\u05d1\u05d5\u05e2\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.deshe-kavua.co.il\/en\/category\/garden-products-en\/\" \/>\n<meta property=\"og:site_name\" content=\"\u05d3\u05e9\u05d0 \u05e7\u05d1\u05d5\u05e2\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.deshe-kavua.co.il\/wp-content\/uploads\/2023\/01\/Mask-Group.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1822\" \/>\n\t<meta property=\"og:image:height\" content=\"752\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"CollectionPage\",\"@id\":\"https:\\\/\\\/www.deshe-kavua.co.il\\\/en\\\/category\\\/garden-products-en\\\/\",\"url\":\"https:\\\/\\\/www.deshe-kavua.co.il\\\/en\\\/category\\\/garden-products-en\\\/\",\"name\":\"Garden Products\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.deshe-kavua.co.il\\\/#website\"},\"description\":\"\u05d3\u05e9\u05d0 \u05e7\u05d1\u05d5\u05e2\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.deshe-kavua.co.il\\\/en\\\/category\\\/garden-products-en\\\/#breadcrumb\"},\"inLanguage\":\"en-US\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.deshe-kavua.co.il\\\/en\\\/category\\\/garden-products-en\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"\u05e8\u05d0\u05e9\u05d9\",\"item\":\"https:\\\/\\\/www.deshe-kavua.co.il\\\/en\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Garden Products\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.deshe-kavua.co.il\\\/#website\",\"url\":\"https:\\\/\\\/www.deshe-kavua.co.il\\\/\",\"name\":\"\u05d3\u05e9\u05d0 \u05e7\u05d1\u05d5\u05e2 - \u05d3\u05e9\u05d0 \u05e1\u05d9\u05e0\u05d8\u05d8\u05d9 \u05d6\u05d5\u05dc \u05d5\u05d0\u05d9\u05db\u05d5\u05ea\u05d9\",\"description\":\"\u05d9\u05d1\u05d5\u05d0\u05df \u05d3\u05e9\u05d0 \u05e1\u05d9\u05e0\u05d8\u05d8\u05d9 \u05de\u05d5\u05d1\u05d9\u05dc \u05d1\u05d9\u05e9\u05e8\u05d0\u05dc \u2014 \u05de\u05d7\u05d9\u05e8\u05d9\u05dd \u05d9\u05e9\u05d9\u05e8\u05d9\u05dd \u05de\u05d4\u05d9\u05d1\u05d5\u05d0\u05df, 5 \u05e9\u05e0\u05d5\u05ea \u05d0\u05d7\u05e8\u05d9\u05d5\u05ea\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.deshe-kavua.co.il\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.deshe-kavua.co.il\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.deshe-kavua.co.il\\\/#organization\",\"name\":\"\u05d3\u05e9\u05d0 \u05e7\u05d1\u05d5\u05e2\",\"url\":\"https:\\\/\\\/www.deshe-kavua.co.il\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/www.deshe-kavua.co.il\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.deshe-kavua.co.il\\\/wp-content\\\/uploads\\\/2023\\\/09\\\/cropped-mobile-top-1.jpg\",\"contentUrl\":\"https:\\\/\\\/www.deshe-kavua.co.il\\\/wp-content\\\/uploads\\\/2023\\\/09\\\/cropped-mobile-top-1.jpg\",\"width\":414,\"height\":179,\"caption\":\"\u05d3\u05e9\u05d0 \u05e7\u05d1\u05d5\u05e2\"},\"image\":{\"@id\":\"https:\\\/\\\/www.deshe-kavua.co.il\\\/#\\\/schema\\\/logo\\\/image\\\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Garden Products","description":"\u05d3\u05e9\u05d0 \u05e7\u05d1\u05d5\u05e2","robots":{"index":"noindex","follow":"follow"},"og_locale":"en_US","og_type":"article","og_title":"Garden Products","og_description":"\u05d3\u05e9\u05d0 \u05e7\u05d1\u05d5\u05e2","og_url":"https:\/\/www.deshe-kavua.co.il\/en\/category\/garden-products-en\/","og_site_name":"\u05d3\u05e9\u05d0 \u05e7\u05d1\u05d5\u05e2","og_image":[{"width":1822,"height":752,"url":"https:\/\/www.deshe-kavua.co.il\/wp-content\/uploads\/2023\/01\/Mask-Group.jpg","type":"image\/jpeg"}],"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"CollectionPage","@id":"https:\/\/www.deshe-kavua.co.il\/en\/category\/garden-products-en\/","url":"https:\/\/www.deshe-kavua.co.il\/en\/category\/garden-products-en\/","name":"Garden Products","isPartOf":{"@id":"https:\/\/www.deshe-kavua.co.il\/#website"},"description":"\u05d3\u05e9\u05d0 \u05e7\u05d1\u05d5\u05e2","breadcrumb":{"@id":"https:\/\/www.deshe-kavua.co.il\/en\/category\/garden-products-en\/#breadcrumb"},"inLanguage":"en-US"},{"@type":"BreadcrumbList","@id":"https:\/\/www.deshe-kavua.co.il\/en\/category\/garden-products-en\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"\u05e8\u05d0\u05e9\u05d9","item":"https:\/\/www.deshe-kavua.co.il\/en\/"},{"@type":"ListItem","position":2,"name":"Garden Products"}]},{"@type":"WebSite","@id":"https:\/\/www.deshe-kavua.co.il\/#website","url":"https:\/\/www.deshe-kavua.co.il\/","name":"\u05d3\u05e9\u05d0 \u05e7\u05d1\u05d5\u05e2 - \u05d3\u05e9\u05d0 \u05e1\u05d9\u05e0\u05d8\u05d8\u05d9 \u05d6\u05d5\u05dc \u05d5\u05d0\u05d9\u05db\u05d5\u05ea\u05d9","description":"\u05d9\u05d1\u05d5\u05d0\u05df \u05d3\u05e9\u05d0 \u05e1\u05d9\u05e0\u05d8\u05d8\u05d9 \u05de\u05d5\u05d1\u05d9\u05dc \u05d1\u05d9\u05e9\u05e8\u05d0\u05dc \u2014 \u05de\u05d7\u05d9\u05e8\u05d9\u05dd \u05d9\u05e9\u05d9\u05e8\u05d9\u05dd \u05de\u05d4\u05d9\u05d1\u05d5\u05d0\u05df, 5 \u05e9\u05e0\u05d5\u05ea \u05d0\u05d7\u05e8\u05d9\u05d5\u05ea","publisher":{"@id":"https:\/\/www.deshe-kavua.co.il\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.deshe-kavua.co.il\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/www.deshe-kavua.co.il\/#organization","name":"\u05d3\u05e9\u05d0 \u05e7\u05d1\u05d5\u05e2","url":"https:\/\/www.deshe-kavua.co.il\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/www.deshe-kavua.co.il\/#\/schema\/logo\/image\/","url":"https:\/\/www.deshe-kavua.co.il\/wp-content\/uploads\/2023\/09\/cropped-mobile-top-1.jpg","contentUrl":"https:\/\/www.deshe-kavua.co.il\/wp-content\/uploads\/2023\/09\/cropped-mobile-top-1.jpg","width":414,"height":179,"caption":"\u05d3\u05e9\u05d0 \u05e7\u05d1\u05d5\u05e2"},"image":{"@id":"https:\/\/www.deshe-kavua.co.il\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/www.deshe-kavua.co.il\/en\/wp-json\/wp\/v2\/categories\/299","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.deshe-kavua.co.il\/en\/wp-json\/wp\/v2\/categories"}],"about":[{"href":"https:\/\/www.deshe-kavua.co.il\/en\/wp-json\/wp\/v2\/taxonomies\/category"}],"wp:post_type":[{"href":"https:\/\/www.deshe-kavua.co.il\/en\/wp-json\/wp\/v2\/posts?categories=299"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}